{"id":26892,"date":"2021-12-16T12:18:40","date_gmt":"2021-12-16T17:18:40","guid":{"rendered":"https:\/\/curaduria4.com.co\/Publicaciones\/?p=26892"},"modified":"2021-12-16T12:19:31","modified_gmt":"2021-12-16T17:19:31","slug":"oficio-no-radicado-001440","status":"publish","type":"post","link":"https:\/\/publicaciones.curaduria4.com.co\/index.php\/2021\/12\/16\/oficio-no-radicado-001440\/","title":{"rendered":"Oficio no Radicado: 001440"},"content":{"rendered":"\n<div class=\"wp-block-file\"><a href=\"https:\/\/curaduria4.com.co\/Publicaciones\/wp-content\/uploads\/2021\/12\/Oficio-no-Radicado-001440.pdf\">Oficio-no-Radicado-001440<\/a><a href=\"https:\/\/curaduria4.com.co\/Publicaciones\/wp-content\/uploads\/2021\/12\/Oficio-no-Radicado-001440.pdf\" class=\"wp-block-file__button\" download>Descargar<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-26892","post","type-post","status-publish","format-standard","hentry","category-comunicados-devueltos-por-correspondencia"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/publicaciones.curaduria4.com.co\/index.php\/wp-json\/wp\/v2\/posts\/26892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/publicaciones.curaduria4.com.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/publicaciones.curaduria4.com.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/publicaciones.curaduria4.com.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/publicaciones.curaduria4.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=26892"}],"version-history":[{"count":2,"href":"https:\/\/publicaciones.curaduria4.com.co\/index.php\/wp-json\/wp\/v2\/posts\/26892\/revisions"}],"predecessor-version":[{"id":26895,"href":"https:\/\/publicaciones.curaduria4.com.co\/index.php\/wp-json\/wp\/v2\/posts\/26892\/revisions\/26895"}],"wp:attachment":[{"href":"https:\/\/publicaciones.curaduria4.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=26892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/publicaciones.curaduria4.com.co\/index.php\/wp-json\/wp\/v2\/categories?post=26892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/publicaciones.curaduria4.com.co\/index.php\/wp-json\/wp\/v2\/tags?post=26892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}